{"id":36095,"date":"2021-08-27T16:25:44","date_gmt":"2021-08-27T12:25:44","guid":{"rendered":"https:\/\/whitestudio.ge\/cart-2\/"},"modified":"2021-08-27T16:25:44","modified_gmt":"2021-08-27T12:25:44","slug":"cart-2","status":"publish","type":"page","link":"https:\/\/whitestudio.ge\/ge\/cart-2\/","title":{"rendered":"Cart"},"content":{"rendered":"\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/pages\/36095"}],"collection":[{"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/comments?post=36095"}],"version-history":[{"count":0,"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/pages\/36095\/revisions"}],"wp:attachment":[{"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/media?parent=36095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}