{"id":26542,"date":"2020-09-02T14:02:43","date_gmt":"2020-09-02T10:02:43","guid":{"rendered":"https:\/\/whitestudio.ge\/product\/ceramics-22319ge\/"},"modified":"2021-08-27T01:59:52","modified_gmt":"2021-08-26T21:59:52","slug":"ceramics-22319ge","status":"publish","type":"product","link":"https:\/\/whitestudio.ge\/ge\/product\/ceramics-22319ge\/","title":{"rendered":"\u10d9\u10d4\u10e0\u10d0\u10db\u10d8\u10d9\u10d0 22319"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[18],"product_tag":[],"_links":{"self":[{"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/product\/26542"}],"collection":[{"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/comments?post=26542"}],"wp:attachment":[{"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/media?parent=26542"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/product_cat?post=26542"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/product_tag?post=26542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}