{"id":80094,"date":"2026-03-24T17:26:58","date_gmt":"2026-03-24T13:26:58","guid":{"rendered":"https:\/\/whitestudio.ge\/product\/%e1%83%a1%e1%83%90%e1%83%90%e1%83%a6%e1%83%93%e1%83%92%e1%83%9d%e1%83%9b%e1%83%9d-%e1%83%99%e1%83%95%e1%83%94%e1%83%a0%e1%83%aa%e1%83%ae%e1%83%98-94\/"},"modified":"2026-03-24T17:26:58","modified_gmt":"2026-03-24T13:26:58","slug":"%e1%83%a1%e1%83%90%e1%83%90%e1%83%a6%e1%83%93%e1%83%92%e1%83%9d%e1%83%9b%e1%83%9d-%e1%83%99%e1%83%95%e1%83%94%e1%83%a0%e1%83%aa%e1%83%ae%e1%83%98-94","status":"publish","type":"product","link":"https:\/\/whitestudio.ge\/ge\/product\/%e1%83%a1%e1%83%90%e1%83%90%e1%83%a6%e1%83%93%e1%83%92%e1%83%9d%e1%83%9b%e1%83%9d-%e1%83%99%e1%83%95%e1%83%94%e1%83%a0%e1%83%aa%e1%83%ae%e1%83%98-94\/","title":{"rendered":"\u10e1\u10d0\u10d0\u10e6\u10d3\u10d2\u10dd\u10db\u10dd \u10d9\u10d5\u10d4\u10e0\u10ea\u10ee\u10d8"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":80093,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[427,429,46],"product_tag":[],"_links":{"self":[{"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/product\/80094"}],"collection":[{"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/comments?post=80094"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/media\/80093"}],"wp:attachment":[{"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/media?parent=80094"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/product_cat?post=80094"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/product_tag?post=80094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}