{"id":80269,"date":"2026-03-27T15:26:10","date_gmt":"2026-03-27T11:26:10","guid":{"rendered":"https:\/\/whitestudio.ge\/product\/%e1%83%a1%e1%83%90%e1%83%90%e1%83%a6%e1%83%93%e1%83%92%e1%83%9d%e1%83%9b%e1%83%9d-%e1%83%a8%e1%83%90%e1%83%9c%e1%83%93%e1%83%90%e1%83%9a%e1%83%98-10\/"},"modified":"2026-03-27T15:26:10","modified_gmt":"2026-03-27T11:26:10","slug":"%e1%83%a1%e1%83%90%e1%83%90%e1%83%a6%e1%83%93%e1%83%92%e1%83%9d%e1%83%9b%e1%83%9d-%e1%83%a8%e1%83%90%e1%83%9c%e1%83%93%e1%83%90%e1%83%9a%e1%83%98-10","status":"publish","type":"product","link":"https:\/\/whitestudio.ge\/ge\/product\/%e1%83%a1%e1%83%90%e1%83%90%e1%83%a6%e1%83%93%e1%83%92%e1%83%9d%e1%83%9b%e1%83%9d-%e1%83%a8%e1%83%90%e1%83%9c%e1%83%93%e1%83%90%e1%83%9a%e1%83%98-10\/","title":{"rendered":"\u10e1\u10d0\u10d0\u10e6\u10d3\u10d2\u10dd\u10db\u10dd \u10e8\u10d0\u10dc\u10d3\u10d0\u10da\u10d8"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":80268,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[427,428,46],"product_tag":[],"_links":{"self":[{"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/product\/80269"}],"collection":[{"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/comments?post=80269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/media\/80268"}],"wp:attachment":[{"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/media?parent=80269"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/product_cat?post=80269"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/product_tag?post=80269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}