{"id":80353,"date":"2026-03-27T17:34:19","date_gmt":"2026-03-27T13:34:19","guid":{"rendered":"https:\/\/whitestudio.ge\/product\/%e1%83%a1%e1%83%90%e1%83%90%e1%83%a6%e1%83%93%e1%83%92%e1%83%9d%e1%83%9b%e1%83%9d-%e1%83%ac%e1%83%95%e1%83%9c%e1%83%98%e1%83%90%e1%83%9c%e1%83%98%e1%83%a1-%e1%83%ad%e1%83%a3%e1%83%a0%e1%83%ad-3\/"},"modified":"2026-03-27T17:34:19","modified_gmt":"2026-03-27T13:34:19","slug":"%e1%83%a1%e1%83%90%e1%83%90%e1%83%a6%e1%83%93%e1%83%92%e1%83%9d%e1%83%9b%e1%83%9d-%e1%83%ac%e1%83%95%e1%83%9c%e1%83%98%e1%83%90%e1%83%9c%e1%83%98%e1%83%a1-%e1%83%ad%e1%83%a3%e1%83%a0%e1%83%ad-3","status":"publish","type":"product","link":"https:\/\/whitestudio.ge\/ge\/product\/%e1%83%a1%e1%83%90%e1%83%90%e1%83%a6%e1%83%93%e1%83%92%e1%83%9d%e1%83%9b%e1%83%9d-%e1%83%ac%e1%83%95%e1%83%9c%e1%83%98%e1%83%90%e1%83%9c%e1%83%98%e1%83%a1-%e1%83%ad%e1%83%a3%e1%83%a0%e1%83%ad-3\/","title":{"rendered":"\u10e1\u10d0\u10d0\u10e6\u10d3\u10d2\u10dd\u10db\u10dd \u10ec\u10d5\u10dc\u10d8\u10d0\u10dc\u10d8\u10e1 \u10ed\u10e3\u10e0\u10ed\u10d4\u10da\u10d8 \u10e7\u10d5\u10d0\u10d5\u10d8\u10da\u10d4\u10d1\u10d8\u10d7"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":80348,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[427,432,46,55,96],"product_tag":[],"_links":{"self":[{"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/product\/80353"}],"collection":[{"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/comments?post=80353"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/media\/80348"}],"wp:attachment":[{"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/media?parent=80353"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/product_cat?post=80353"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/whitestudio.ge\/ge\/wp-json\/wp\/v2\/product_tag?post=80353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}